{"id":37684,"date":"2011-08-20T15:24:57","date_gmt":"2011-08-20T15:24:57","guid":{"rendered":"http:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/"},"modified":"2011-08-20T15:24:57","modified_gmt":"2011-08-20T15:24:57","slug":"pacific-sun-leather-bears-scene-3","status":"publish","type":"post","link":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/","title":{"rendered":"Pacific sun &#8211; leather bears &#8211; scene 3"},"content":{"rendered":"<p><!--videoplayer--><object width=\"430\" height=\"350\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/fpdownload.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=8,0,0,0\" ><param name=\"quality\" value=\"high\" \/><param name=\"bgcolor\" value=\"#000000\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><param name=\"movie\" value=\"http:\/\/www.xvideos.com\/sitevideos\/flv_player_site_v4.swf\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"flashvars\" value=\"id_video=1283671\/THUMBNUM\" \/><embed src=\"http:\/\/www.xvideos.com\/sitevideos\/flv_player_site_v4.swf\" allowscriptaccess=\"always\" width=\"430\" height=\"350\" menu=\"false\" quality=\"high\" bgcolor=\"#000000\" allowfullscreen=\"true\" flashvars=\"id_video=1283671\/THUMBNUM\" type=\"application\/x-shockwave-flash\" pluginspage=\"http:\/\/www.macromedia.com\/go\/getflashplayer\" \/><\/object><!--endvideoplayer--><br \/>\n<img decoding=\"async\" src=\"http:\/\/phonesexwow.com\/domination-banner.jpg\" border=\"0\" alt=\"cheap phone sex\"><br \/>\nPacific sun &#8211; leather bears &#8211; scene 3<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pacific sun &#8211; leather bears &#8211; scene 3<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[26225,13393,901,3366],"class_list":["post-37684","post","type-post","status-publish","format-standard","hentry","category-phone-sex","tag-leatbears","tag-pacific","tag-scen","tag-sun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pacific sun - leather bears - scene 3 - Phone Sex Video and Porn Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pacific sun - leather bears - scene 3 - Phone Sex Video and Porn Blog\" \/>\n<meta property=\"og:description\" content=\"Pacific sun &#8211; leather bears &#8211; scene 3\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Phone Sex Video and Porn Blog\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-20T15:24:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/phonesexwow.com\/domination-banner.jpg\" \/>\n<meta name=\"author\" content=\"Phone Sex Wow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Phone Sex Wow\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/\"},\"author\":{\"name\":\"Phone Sex Wow\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\"},\"headline\":\"Pacific sun &#8211; leather bears &#8211; scene 3\",\"datePublished\":\"2011-08-20T15:24:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/\"},\"wordCount\":14,\"image\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"keywords\":[\"leatbears\",\"pacific\",\"scen\",\"sun\"],\"articleSection\":[\"Phone Sex\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/\",\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/\",\"name\":\"Pacific sun - leather bears - scene 3 - Phone Sex Video and Porn Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"datePublished\":\"2011-08-20T15:24:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/#primaryimage\",\"url\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"contentUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/08\\\/pacific-sun-leather-bears-scene-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pacific sun &#8211; leather bears &#8211; scene 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/\",\"name\":\"Phone Sex Video and Porn Blog\",\"description\":\"Watch Phone Sex Videos and Porn Videos for FREE!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\",\"name\":\"Phone Sex Wow\",\"sameAs\":[\"http:\\\/\\\/phonesexwow.com\"],\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pacific sun - leather bears - scene 3 - Phone Sex Video and Porn Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/","og_locale":"en_US","og_type":"article","og_title":"Pacific sun - leather bears - scene 3 - Phone Sex Video and Porn Blog","og_description":"Pacific sun &#8211; leather bears &#8211; scene 3","og_url":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/","og_site_name":"Phone Sex Video and Porn Blog","article_published_time":"2011-08-20T15:24:57+00:00","og_image":[{"url":"http:\/\/phonesexwow.com\/domination-banner.jpg","type":"","width":"","height":""}],"author":"Phone Sex Wow","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Phone Sex Wow"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/#article","isPartOf":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/"},"author":{"name":"Phone Sex Wow","@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c"},"headline":"Pacific sun &#8211; leather bears &#8211; scene 3","datePublished":"2011-08-20T15:24:57+00:00","mainEntityOfPage":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/"},"wordCount":14,"image":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/#primaryimage"},"thumbnailUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg","keywords":["leatbears","pacific","scen","sun"],"articleSection":["Phone Sex"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/","url":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/","name":"Pacific sun - leather bears - scene 3 - Phone Sex Video and Porn Blog","isPartOf":{"@id":"https:\/\/phonesexwow.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/#primaryimage"},"image":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/#primaryimage"},"thumbnailUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg","datePublished":"2011-08-20T15:24:57+00:00","author":{"@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c"},"breadcrumb":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/#primaryimage","url":"http:\/\/phonesexwow.com\/domination-banner.jpg","contentUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/phonesexwow.com\/blog\/2011\/08\/pacific-sun-leather-bears-scene-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/phonesexwow.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Pacific sun &#8211; leather bears &#8211; scene 3"}]},{"@type":"WebSite","@id":"https:\/\/phonesexwow.com\/blog\/#website","url":"https:\/\/phonesexwow.com\/blog\/","name":"Phone Sex Video and Porn Blog","description":"Watch Phone Sex Videos and Porn Videos for FREE!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phonesexwow.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c","name":"Phone Sex Wow","sameAs":["http:\/\/phonesexwow.com"],"url":"https:\/\/phonesexwow.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts\/37684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/comments?post=37684"}],"version-history":[{"count":0,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts\/37684\/revisions"}],"wp:attachment":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/media?parent=37684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/categories?post=37684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/tags?post=37684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}