{"id":35431,"date":"2011-05-27T15:22:43","date_gmt":"2011-05-27T15:22:43","guid":{"rendered":"http:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/"},"modified":"2011-05-27T15:22:43","modified_gmt":"2011-05-27T15:22:43","slug":"carmela-bing-gets-cummed-on-her-big-tits","status":"publish","type":"post","link":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/","title":{"rendered":"Carmela bing gets cummed on her big tits"},"content":{"rendered":"<p><!--videoplayer--><embed src=\"http:\/\/www.deviantclip.com\/flashplayer\/flvplayer.swf\" width=\"430\" height=\"350\" menu=\"false\" quality=\"high\" bgcolor=\"#ffffff\" wmode=\"transparent\" allowfullscreen=\"true\" allowscriptaccess=\"always\" flashvars=\"enablejs=true&#038;autostart=false&#038;mediaid=111901&#038;displayclick=link&#038;linktarget=_blank&#038;backcolor=0xcd9b8d&#038;frontcolor=0xebdbd4&#038;lightcolor=0xffffff&#038;streamer=lighttpd\" type=\"application\/x-shockwave-flash\" pluginspage=\"http:\/\/www.macromedia.com\/go\/getflashplayer\" \/><!--endvideoplayer--><br \/>\n<img decoding=\"async\" src=\"http:\/\/phonesexwow.com\/domination-banner.jpg\" border=\"0\" alt=\"cheap phone sex\"><br \/>\nCarmela bing gets cummed on her big tits<br \/>\n&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carmela bing gets cummed on her big tits &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[185,24977,2299,297],"class_list":["post-35431","post","type-post","status-publish","format-standard","hentry","category-phone-sex","tag-big","tag-carmelbing","tag-cummed","tag-tits"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carmela bing gets cummed on her big tits - Phone Sex Video and Porn Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carmela bing gets cummed on her big tits - Phone Sex Video and Porn Blog\" \/>\n<meta property=\"og:description\" content=\"Carmela bing gets cummed on her big tits &#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/\" \/>\n<meta property=\"og:site_name\" content=\"Phone Sex Video and Porn Blog\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-27T15:22:43+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/phonesexwow.com\/domination-banner.jpg\" \/>\n<meta name=\"author\" content=\"Phone Sex Wow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Phone Sex Wow\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/\"},\"author\":{\"name\":\"Phone Sex Wow\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\"},\"headline\":\"Carmela bing gets cummed on her big tits\",\"datePublished\":\"2011-05-27T15:22:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/\"},\"wordCount\":16,\"image\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"keywords\":[\"Big\",\"carmelbing\",\"Cummed\",\"Tits\"],\"articleSection\":[\"Phone Sex\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/\",\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/\",\"name\":\"Carmela bing gets cummed on her big tits - Phone Sex Video and Porn Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"datePublished\":\"2011-05-27T15:22:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/#primaryimage\",\"url\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"contentUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/05\\\/carmela-bing-gets-cummed-on-her-big-tits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carmela bing gets cummed on her big tits\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/\",\"name\":\"Phone Sex Video and Porn Blog\",\"description\":\"Watch Phone Sex Videos and Porn Videos for FREE!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\",\"name\":\"Phone Sex Wow\",\"sameAs\":[\"http:\\\/\\\/phonesexwow.com\"],\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carmela bing gets cummed on her big tits - Phone Sex Video and Porn Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/","og_locale":"en_US","og_type":"article","og_title":"Carmela bing gets cummed on her big tits - Phone Sex Video and Porn Blog","og_description":"Carmela bing gets cummed on her big tits &#8230;","og_url":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/","og_site_name":"Phone Sex Video and Porn Blog","article_published_time":"2011-05-27T15:22:43+00:00","og_image":[{"url":"http:\/\/phonesexwow.com\/domination-banner.jpg","type":"","width":"","height":""}],"author":"Phone Sex Wow","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Phone Sex Wow"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/#article","isPartOf":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/"},"author":{"name":"Phone Sex Wow","@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c"},"headline":"Carmela bing gets cummed on her big tits","datePublished":"2011-05-27T15:22:43+00:00","mainEntityOfPage":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/"},"wordCount":16,"image":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/#primaryimage"},"thumbnailUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg","keywords":["Big","carmelbing","Cummed","Tits"],"articleSection":["Phone Sex"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/","url":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/","name":"Carmela bing gets cummed on her big tits - Phone Sex Video and Porn Blog","isPartOf":{"@id":"https:\/\/phonesexwow.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/#primaryimage"},"image":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/#primaryimage"},"thumbnailUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg","datePublished":"2011-05-27T15:22:43+00:00","author":{"@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c"},"breadcrumb":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/#primaryimage","url":"http:\/\/phonesexwow.com\/domination-banner.jpg","contentUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/phonesexwow.com\/blog\/2011\/05\/carmela-bing-gets-cummed-on-her-big-tits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/phonesexwow.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Carmela bing gets cummed on her big tits"}]},{"@type":"WebSite","@id":"https:\/\/phonesexwow.com\/blog\/#website","url":"https:\/\/phonesexwow.com\/blog\/","name":"Phone Sex Video and Porn Blog","description":"Watch Phone Sex Videos and Porn Videos for FREE!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phonesexwow.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c","name":"Phone Sex Wow","sameAs":["http:\/\/phonesexwow.com"],"url":"https:\/\/phonesexwow.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts\/35431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/comments?post=35431"}],"version-history":[{"count":0,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts\/35431\/revisions"}],"wp:attachment":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/media?parent=35431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/categories?post=35431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/tags?post=35431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}