{"id":32174,"date":"2011-03-20T15:27:20","date_gmt":"2011-03-20T15:27:20","guid":{"rendered":"http:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/"},"modified":"2011-03-20T15:27:20","modified_gmt":"2011-03-20T15:27:20","slug":"small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick","status":"publish","type":"post","link":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/","title":{"rendered":"Small breasted japanese girl kanade asamiya riding a massive dick"},"content":{"rendered":"<p><!--videoplayer--><embed src=\"http:\/\/www.deviantclip.com\/flashplayer\/flvplayer.swf\" width=\"430\" height=\"350\" menu=\"false\" quality=\"high\" bgcolor=\"#ffffff\" wmode=\"transparent\" allowfullscreen=\"true\" allowscriptaccess=\"always\" flashvars=\"enablejs=true&#038;autostart=false&#038;mediaid=71869&#038;displayclick=link&#038;linktarget=_blank&#038;backcolor=0xcd9b8d&#038;frontcolor=0xebdbd4&#038;lightcolor=0xffffff&#038;streamer=lighttpd\" type=\"application\/x-shockwave-flash\" pluginspage=\"http:\/\/www.macromedia.com\/go\/getflashplayer\" \/><!--endvideoplayer--><br \/>\n<img decoding=\"async\" src=\"http:\/\/phonesexwow.com\/domination-banner.jpg\" border=\"0\" alt=\"cheap phone sex\"><br \/>\nSmall breasted japanese girl kanade asamiya riding a massive dick<br \/>\n&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Small breasted japanese girl kanade asamiya riding a massive dick &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[3589,12707,8944,446],"class_list":["post-32174","post","type-post","status-publish","format-standard","hentry","category-phone-sex","tag-japanesgirl","tag-kanadasamiyriding","tag-massivdick","tag-small"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Small breasted japanese girl kanade asamiya riding a massive dick - Phone Sex Video and Porn Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Small breasted japanese girl kanade asamiya riding a massive dick - Phone Sex Video and Porn Blog\" \/>\n<meta property=\"og:description\" content=\"Small breasted japanese girl kanade asamiya riding a massive dick &#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/\" \/>\n<meta property=\"og:site_name\" content=\"Phone Sex Video and Porn Blog\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-20T15:27:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/phonesexwow.com\/domination-banner.jpg\" \/>\n<meta name=\"author\" content=\"Phone Sex Wow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Phone Sex Wow\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/\"},\"author\":{\"name\":\"Phone Sex Wow\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\"},\"headline\":\"Small breasted japanese girl kanade asamiya riding a massive dick\",\"datePublished\":\"2011-03-20T15:27:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/\"},\"wordCount\":20,\"image\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"keywords\":[\"japanesgirl\",\"kanadasamiyriding\",\"massivdick\",\"Small\"],\"articleSection\":[\"Phone Sex\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/\",\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/\",\"name\":\"Small breasted japanese girl kanade asamiya riding a massive dick - Phone Sex Video and Porn Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"datePublished\":\"2011-03-20T15:27:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/#primaryimage\",\"url\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"contentUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2011\\\/03\\\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Small breasted japanese girl kanade asamiya riding a massive dick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/\",\"name\":\"Phone Sex Video and Porn Blog\",\"description\":\"Watch Phone Sex Videos and Porn Videos for FREE!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\",\"name\":\"Phone Sex Wow\",\"sameAs\":[\"http:\\\/\\\/phonesexwow.com\"],\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Small breasted japanese girl kanade asamiya riding a massive dick - Phone Sex Video and Porn Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/","og_locale":"en_US","og_type":"article","og_title":"Small breasted japanese girl kanade asamiya riding a massive dick - Phone Sex Video and Porn Blog","og_description":"Small breasted japanese girl kanade asamiya riding a massive dick &#8230;","og_url":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/","og_site_name":"Phone Sex Video and Porn Blog","article_published_time":"2011-03-20T15:27:20+00:00","og_image":[{"url":"http:\/\/phonesexwow.com\/domination-banner.jpg","type":"","width":"","height":""}],"author":"Phone Sex Wow","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Phone Sex Wow"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/#article","isPartOf":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/"},"author":{"name":"Phone Sex Wow","@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c"},"headline":"Small breasted japanese girl kanade asamiya riding a massive dick","datePublished":"2011-03-20T15:27:20+00:00","mainEntityOfPage":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/"},"wordCount":20,"image":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/#primaryimage"},"thumbnailUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg","keywords":["japanesgirl","kanadasamiyriding","massivdick","Small"],"articleSection":["Phone Sex"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/","url":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/","name":"Small breasted japanese girl kanade asamiya riding a massive dick - Phone Sex Video and Porn Blog","isPartOf":{"@id":"https:\/\/phonesexwow.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/#primaryimage"},"image":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/#primaryimage"},"thumbnailUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg","datePublished":"2011-03-20T15:27:20+00:00","author":{"@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c"},"breadcrumb":{"@id":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/#primaryimage","url":"http:\/\/phonesexwow.com\/domination-banner.jpg","contentUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/phonesexwow.com\/blog\/2011\/03\/small-breasted-japanese-girl-kanade-asamiya-riding-a-massive-dick\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/phonesexwow.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Small breasted japanese girl kanade asamiya riding a massive dick"}]},{"@type":"WebSite","@id":"https:\/\/phonesexwow.com\/blog\/#website","url":"https:\/\/phonesexwow.com\/blog\/","name":"Phone Sex Video and Porn Blog","description":"Watch Phone Sex Videos and Porn Videos for FREE!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phonesexwow.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c","name":"Phone Sex Wow","sameAs":["http:\/\/phonesexwow.com"],"url":"https:\/\/phonesexwow.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts\/32174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/comments?post=32174"}],"version-history":[{"count":0,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts\/32174\/revisions"}],"wp:attachment":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/media?parent=32174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/categories?post=32174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/tags?post=32174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}