{"id":19473,"date":"2010-09-04T15:23:38","date_gmt":"2010-09-04T15:23:38","guid":{"rendered":"http:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/"},"modified":"2010-09-04T15:23:38","modified_gmt":"2010-09-04T15:23:38","slug":"sophie-dee-facesitting-love-this-girl","status":"publish","type":"post","link":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/","title":{"rendered":"Sophie dee facesitting love this girl"},"content":{"rendered":"<p><!--videoplayer--><object width=\"430\" height=\"350\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/fpdownload.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=8,0,0,0\" ><param name=\"quality\" value=\"high\" \/><param name=\"bgcolor\" value=\"#000000\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><param name=\"movie\" value=\"http:\/\/www.xvideos.com\/sitevideos\/flv_player_site_v4.swf\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"flashvars\" value=\"id_video=589812\" \/><embed src=\"http:\/\/www.xvideos.com\/sitevideos\/flv_player_site_v4.swf\" allowscriptaccess=\"always\" width=\"430\" height=\"350\" menu=\"false\" quality=\"high\" bgcolor=\"#000000\" allowfullscreen=\"true\" flashvars=\"id_video=589812\" type=\"application\/x-shockwave-flash\" pluginspage=\"http:\/\/www.macromedia.com\/go\/getflashplayer\" \/><\/object><!--endvideoplayer--><br \/>\n<img decoding=\"async\" src=\"http:\/\/phonesexwow.com\/domination-banner.jpg\" border=\"0\" alt=\"cheap phone sex\"><br \/>\nSophie dee facesitting love this girl<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sophie dee facesitting love this girl<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[17083,17082],"class_list":["post-19473","post","type-post","status-publish","format-standard","hentry","category-phone-sex","tag-lovthgirl","tag-sophidefacesitting"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sophie dee facesitting love this girl - Phone Sex Video and Porn Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sophie dee facesitting love this girl - Phone Sex Video and Porn Blog\" \/>\n<meta property=\"og:description\" content=\"Sophie dee facesitting love this girl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/\" \/>\n<meta property=\"og:site_name\" content=\"Phone Sex Video and Porn Blog\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-04T15:23:38+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/phonesexwow.com\/domination-banner.jpg\" \/>\n<meta name=\"author\" content=\"Phone Sex Wow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Phone Sex Wow\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/\"},\"author\":{\"name\":\"Phone Sex Wow\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\"},\"headline\":\"Sophie dee facesitting love this girl\",\"datePublished\":\"2010-09-04T15:23:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/\"},\"wordCount\":12,\"image\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"keywords\":[\"lovthgirl\",\"sophidefacesitting\"],\"articleSection\":[\"Phone Sex\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/\",\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/\",\"name\":\"Sophie dee facesitting love this girl - Phone Sex Video and Porn Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"datePublished\":\"2010-09-04T15:23:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/#primaryimage\",\"url\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"contentUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/09\\\/sophie-dee-facesitting-love-this-girl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sophie dee facesitting love this girl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/\",\"name\":\"Phone Sex Video and Porn Blog\",\"description\":\"Watch Phone Sex Videos and Porn Videos for FREE!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\",\"name\":\"Phone Sex Wow\",\"sameAs\":[\"http:\\\/\\\/phonesexwow.com\"],\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sophie dee facesitting love this girl - Phone Sex Video and Porn Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/","og_locale":"en_US","og_type":"article","og_title":"Sophie dee facesitting love this girl - Phone Sex Video and Porn Blog","og_description":"Sophie dee facesitting love this girl","og_url":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/","og_site_name":"Phone Sex Video and Porn Blog","article_published_time":"2010-09-04T15:23:38+00:00","og_image":[{"url":"http:\/\/phonesexwow.com\/domination-banner.jpg","type":"","width":"","height":""}],"author":"Phone Sex Wow","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Phone Sex Wow"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/#article","isPartOf":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/"},"author":{"name":"Phone Sex Wow","@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c"},"headline":"Sophie dee facesitting love this girl","datePublished":"2010-09-04T15:23:38+00:00","mainEntityOfPage":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/"},"wordCount":12,"image":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/#primaryimage"},"thumbnailUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg","keywords":["lovthgirl","sophidefacesitting"],"articleSection":["Phone Sex"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/","url":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/","name":"Sophie dee facesitting love this girl - Phone Sex Video and Porn Blog","isPartOf":{"@id":"https:\/\/phonesexwow.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/#primaryimage"},"image":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/#primaryimage"},"thumbnailUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg","datePublished":"2010-09-04T15:23:38+00:00","author":{"@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c"},"breadcrumb":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/#primaryimage","url":"http:\/\/phonesexwow.com\/domination-banner.jpg","contentUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/phonesexwow.com\/blog\/2010\/09\/sophie-dee-facesitting-love-this-girl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/phonesexwow.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Sophie dee facesitting love this girl"}]},{"@type":"WebSite","@id":"https:\/\/phonesexwow.com\/blog\/#website","url":"https:\/\/phonesexwow.com\/blog\/","name":"Phone Sex Video and Porn Blog","description":"Watch Phone Sex Videos and Porn Videos for FREE!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phonesexwow.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c","name":"Phone Sex Wow","sameAs":["http:\/\/phonesexwow.com"],"url":"https:\/\/phonesexwow.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts\/19473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/comments?post=19473"}],"version-history":[{"count":0,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts\/19473\/revisions"}],"wp:attachment":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/media?parent=19473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/categories?post=19473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/tags?post=19473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}