{"id":17616,"date":"2010-07-28T15:19:47","date_gmt":"2010-07-28T15:19:47","guid":{"rendered":"http:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/"},"modified":"2010-07-28T15:19:47","modified_gmt":"2010-07-28T15:19:47","slug":"dawn-kelly-dirty-little-trash-talkers-scene-4","status":"publish","type":"post","link":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/","title":{"rendered":"Dawn kelly &#8211; dirty little trash talkers &#8211; scene 4"},"content":{"rendered":"<p><!--videoplayer--><object type=\"application\/x-shockwave-flash\" data=\"http:\/\/ph-static.phncdn.com\/flash\/embed_player_v1.3.swf\" width=\"430\" height=\"350\"><param name=\"movie\" value=\"http:\/\/ph-static.phncdn.com\/flash\/embed_player_v1.3.swf\" \/><param name=\"bgColor\" value=\"#000000\" \/><param name=\"allowfullscreen\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><param name=\"FlashVars\" value=\"options=http:\/\/www.pornhub.com\/embed_player.php?id=94581\"\/><\/object><!--endvideoplayer--><br \/>\n<img decoding=\"async\" src=\"http:\/\/phonesexwow.com\/domination-banner.jpg\" border=\"0\" alt=\"cheap phone sex\"><br \/>\nDawn kelly &#8211; dirty little trash talkers &#8211; scene 4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dawn kelly &#8211; dirty little trash talkers &#8211; scene 4<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[14674,40,1008,15611,15628,15612],"class_list":["post-17616","post","type-post","status-publish","format-standard","hentry","category-phone-sex","tag-dawn","tag-dirty","tag-kelly","tag-littltrash","tag-scen4","tag-talkers"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dawn kelly - dirty little trash talkers - scene 4 - Phone Sex Video and Porn Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dawn kelly - dirty little trash talkers - scene 4 - Phone Sex Video and Porn Blog\" \/>\n<meta property=\"og:description\" content=\"Dawn kelly &#8211; dirty little trash talkers &#8211; scene 4\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Phone Sex Video and Porn Blog\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-28T15:19:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/phonesexwow.com\/domination-banner.jpg\" \/>\n<meta name=\"author\" content=\"Phone Sex Wow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Phone Sex Wow\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/\"},\"author\":{\"name\":\"Phone Sex Wow\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\"},\"headline\":\"Dawn kelly &#8211; dirty little trash talkers &#8211; scene 4\",\"datePublished\":\"2010-07-28T15:19:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/\"},\"wordCount\":18,\"image\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"keywords\":[\"dawn\",\"dirty\",\"Kelly\",\"littltrash\",\"scen4\",\"talkers\"],\"articleSection\":[\"Phone Sex\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/\",\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/\",\"name\":\"Dawn kelly - dirty little trash talkers - scene 4 - Phone Sex Video and Porn Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"datePublished\":\"2010-07-28T15:19:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/#primaryimage\",\"url\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\",\"contentUrl\":\"http:\\\/\\\/phonesexwow.com\\\/domination-banner.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/2010\\\/07\\\/dawn-kelly-dirty-little-trash-talkers-scene-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dawn kelly &#8211; dirty little trash talkers &#8211; scene 4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/\",\"name\":\"Phone Sex Video and Porn Blog\",\"description\":\"Watch Phone Sex Videos and Porn Videos for FREE!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/#\\\/schema\\\/person\\\/74725f398d982a995a7b350d3075b09c\",\"name\":\"Phone Sex Wow\",\"sameAs\":[\"http:\\\/\\\/phonesexwow.com\"],\"url\":\"https:\\\/\\\/phonesexwow.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dawn kelly - dirty little trash talkers - scene 4 - Phone Sex Video and Porn Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/","og_locale":"en_US","og_type":"article","og_title":"Dawn kelly - dirty little trash talkers - scene 4 - Phone Sex Video and Porn Blog","og_description":"Dawn kelly &#8211; dirty little trash talkers &#8211; scene 4","og_url":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/","og_site_name":"Phone Sex Video and Porn Blog","article_published_time":"2010-07-28T15:19:47+00:00","og_image":[{"url":"http:\/\/phonesexwow.com\/domination-banner.jpg","type":"","width":"","height":""}],"author":"Phone Sex Wow","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Phone Sex Wow"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/#article","isPartOf":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/"},"author":{"name":"Phone Sex Wow","@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c"},"headline":"Dawn kelly &#8211; dirty little trash talkers &#8211; scene 4","datePublished":"2010-07-28T15:19:47+00:00","mainEntityOfPage":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/"},"wordCount":18,"image":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/#primaryimage"},"thumbnailUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg","keywords":["dawn","dirty","Kelly","littltrash","scen4","talkers"],"articleSection":["Phone Sex"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/","url":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/","name":"Dawn kelly - dirty little trash talkers - scene 4 - Phone Sex Video and Porn Blog","isPartOf":{"@id":"https:\/\/phonesexwow.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/#primaryimage"},"image":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/#primaryimage"},"thumbnailUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg","datePublished":"2010-07-28T15:19:47+00:00","author":{"@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c"},"breadcrumb":{"@id":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/#primaryimage","url":"http:\/\/phonesexwow.com\/domination-banner.jpg","contentUrl":"http:\/\/phonesexwow.com\/domination-banner.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/phonesexwow.com\/blog\/2010\/07\/dawn-kelly-dirty-little-trash-talkers-scene-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/phonesexwow.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Dawn kelly &#8211; dirty little trash talkers &#8211; scene 4"}]},{"@type":"WebSite","@id":"https:\/\/phonesexwow.com\/blog\/#website","url":"https:\/\/phonesexwow.com\/blog\/","name":"Phone Sex Video and Porn Blog","description":"Watch Phone Sex Videos and Porn Videos for FREE!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phonesexwow.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/phonesexwow.com\/blog\/#\/schema\/person\/74725f398d982a995a7b350d3075b09c","name":"Phone Sex Wow","sameAs":["http:\/\/phonesexwow.com"],"url":"https:\/\/phonesexwow.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts\/17616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/comments?post=17616"}],"version-history":[{"count":0,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/posts\/17616\/revisions"}],"wp:attachment":[{"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/media?parent=17616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/categories?post=17616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phonesexwow.com\/blog\/wp-json\/wp\/v2\/tags?post=17616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}